{"id":138,"date":"2023-12-28T16:35:21","date_gmt":"2023-12-28T16:35:21","guid":{"rendered":"https:\/\/fondalpress.it\/?p=138"},"modified":"2024-06-21T04:36:52","modified_gmt":"2024-06-21T04:36:52","slug":"riconoscimento","status":"publish","type":"post","link":"https:\/\/fondalpress.it\/de\/riconoscimento\/","title":{"rendered":"Riconoscimento"},"content":{"rendered":"<p style=\"text-align: left;\"><strong>Riconoscimento per resilienza, intraprendenza e successo<\/strong><\/p>\n<p style=\"text-align: left;\">Siamo felici e orgogliosi di annunciare che la nostra Presidente Maria Grazia Doglione \u00e8 stata insignita dell&#8217;IWEC Award 2023, il prestigioso riconoscimento assegnato alle donne che con la loro esperienza di intraprendenza e successo possono essere d&#8217;ispirazione ad altre colleghe. Felicitazioni!<\/p>\n<p style=\"text-align: left;\">\u00c8l&#8217;astigiana Maria Grazia Doglione, presidente di Fondalpress azienda specializzata nella pressocolatura di leghe d&#8217;alluminio, l&#8217;imprenditrice insignita dell&#8217;Iwec Award 2023, il prestigioso premio assegnato a coloro che possono essere di ispirazione per altre colleghe con la propria esperienza di intraprendenza e successo.<br \/>\n&#8220;\u00c8 un grande onore questo riconoscimento che mi rende orgogliosa anche perch\u00e9 giunge in occasione del cinquantesimo anniversario della fondazione della mia azienda.<\/p>\n<p style=\"text-align: left;\">Esprime il coronamento di un impegno anche associativo che perseguo da tempo: condividere la mia esperienza imprenditoriale e promuovere l&#8217;internazionalizzazione \u00e8 l&#8217;impegno che assumo come awardee Iwec, attivit\u00e0 che caratterizza anche la mia partecipazione alla vita di Aidda, a cui sono molto grata di avere proposto la mia candidatura&#8221; spiega Doglione.<br \/>\n&#8220;Aidda ha accolto con entusiasmo l&#8217;opportunit\u00e0 di sostenere l&#8217;incontro torinese della Fondazione Iwec organizzato dalla Camera di commercio di Torino. La delegazione piemontese ha partecipato con interesse ai panel e agli incontri con le imprenditrici internazionali su temi focali per le nostre attivit\u00e0.<br \/>\nE inoltre una imprenditrice della delegazione piemontese di AIDDA \u00e8 stata insignita dell&#8217;Iwec Award, a testimonianza della qualit\u00e0 dell&#8217;imprenditorialit\u00e0 del nostro territorio&#8221; commenta Valeria Panini, presidente delegazione Piemonte e Valle d&#8217;Aosta.<\/p>","protected":false},"excerpt":{"rendered":"<p>Riconoscimento per resilienza, intraprendenza e successo Siamo felici e orgogliosi di annunciare che la nostra Presidente Maria Grazia Doglione \u00e8 stata insignita dell&#8217;IWEC Award 2023, il prestigioso riconoscimento assegnato alle donne che con la loro esperienza di intraprendenza e successo possono essere d&#8217;ispirazione ad altre colleghe. Felicitazioni! \u00c8l&#8217;astigiana Maria Grazia Doglione, presidente di Fondalpress azienda [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary metaswiss-read-more-link\" href=\"https:\/\/fondalpress.it\/de\/riconoscimento\/\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-ed-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riconoscimento | Fondalpress Spa<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riconoscimento | Fondalpress Spa\" \/>\n<meta property=\"og:description\" content=\"Riconoscimento per resilienza, intraprendenza e successo Siamo felici e orgogliosi di annunciare che la nostra Presidente Maria Grazia Doglione \u00e8 stata insignita dell&#8217;IWEC Award 2023, il prestigioso riconoscimento assegnato alle donne che con la loro esperienza di intraprendenza e successo possono essere d&#8217;ispirazione ad altre colleghe. Felicitazioni! \u00c8l&#8217;astigiana Maria Grazia Doglione, presidente di Fondalpress azienda [...]Weiterlesen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondalpress.it\/de\/riconoscimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondalpress Spa\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T16:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T04:36:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/b3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"9p8rf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"9p8rf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/\"},\"author\":{\"name\":\"9p8rf\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#\\\/schema\\\/person\\\/2803dd62ef580b5b3a488fe8d9ead038\"},\"headline\":\"Riconoscimento\",\"datePublished\":\"2023-12-28T16:35:21+00:00\",\"dateModified\":\"2024-06-21T04:36:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fondalpress.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/b3.webp\",\"articleSection\":[\"News ed eventi\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/\",\"url\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/\",\"name\":\"Riconoscimento | Fondalpress Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fondalpress.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/b3.webp\",\"datePublished\":\"2023-12-28T16:35:21+00:00\",\"dateModified\":\"2024-06-21T04:36:52+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/riconoscimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fondalpress.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/b3.webp\",\"contentUrl\":\"https:\\\/\\\/fondalpress.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/b3.webp\",\"width\":850,\"height\":478},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#website\",\"url\":\"https:\\\/\\\/fondalpress.it\\\/\",\"name\":\"Fondalpress\",\"description\":\"High Pressure Die-casting of Aluminium Alloys\",\"publisher\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fondalpress.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#organization\",\"name\":\"Fondalpress\",\"url\":\"https:\\\/\\\/fondalpress.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fondalpress.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-dark.png\",\"contentUrl\":\"https:\\\/\\\/fondalpress.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-dark.png\",\"width\":374,\"height\":41,\"caption\":\"Fondalpress\"},\"image\":{\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fondalpress.it\\\/#\\\/schema\\\/person\\\/2803dd62ef580b5b3a488fe8d9ead038\",\"name\":\"9p8rf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f05c451de1e00b26ac8f97e593218f403bdeec68c79d0f285b9cd8ca6b14a25f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f05c451de1e00b26ac8f97e593218f403bdeec68c79d0f285b9cd8ca6b14a25f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f05c451de1e00b26ac8f97e593218f403bdeec68c79d0f285b9cd8ca6b14a25f?s=96&d=mm&r=g\",\"caption\":\"9p8rf\"},\"sameAs\":[\"https:\\\/\\\/fondalpress.it\"],\"url\":\"https:\\\/\\\/fondalpress.it\\\/de\\\/author\\\/9p8rf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riconoscimento | Fondalpress Spa","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Riconoscimento | Fondalpress Spa","og_description":"Riconoscimento per resilienza, intraprendenza e successo Siamo felici e orgogliosi di annunciare che la nostra Presidente Maria Grazia Doglione \u00e8 stata insignita dell&#8217;IWEC Award 2023, il prestigioso riconoscimento assegnato alle donne che con la loro esperienza di intraprendenza e successo possono essere d&#8217;ispirazione ad altre colleghe. Felicitazioni! \u00c8l&#8217;astigiana Maria Grazia Doglione, presidente di Fondalpress azienda [...]Weiterlesen...","og_url":"https:\/\/fondalpress.it\/de\/riconoscimento\/","og_site_name":"Fondalpress Spa","article_published_time":"2023-12-28T16:35:21+00:00","article_modified_time":"2024-06-21T04:36:52+00:00","og_image":[{"width":850,"height":478,"url":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/b3.webp","type":"image\/webp"}],"author":"9p8rf","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"9p8rf","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fondalpress.it\/riconoscimento\/#article","isPartOf":{"@id":"https:\/\/fondalpress.it\/riconoscimento\/"},"author":{"name":"9p8rf","@id":"https:\/\/fondalpress.it\/#\/schema\/person\/2803dd62ef580b5b3a488fe8d9ead038"},"headline":"Riconoscimento","datePublished":"2023-12-28T16:35:21+00:00","dateModified":"2024-06-21T04:36:52+00:00","mainEntityOfPage":{"@id":"https:\/\/fondalpress.it\/riconoscimento\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/fondalpress.it\/#organization"},"image":{"@id":"https:\/\/fondalpress.it\/riconoscimento\/#primaryimage"},"thumbnailUrl":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/b3.webp","articleSection":["News ed eventi"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fondalpress.it\/riconoscimento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fondalpress.it\/riconoscimento\/","url":"https:\/\/fondalpress.it\/riconoscimento\/","name":"Riconoscimento | Fondalpress Spa","isPartOf":{"@id":"https:\/\/fondalpress.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondalpress.it\/riconoscimento\/#primaryimage"},"image":{"@id":"https:\/\/fondalpress.it\/riconoscimento\/#primaryimage"},"thumbnailUrl":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/b3.webp","datePublished":"2023-12-28T16:35:21+00:00","dateModified":"2024-06-21T04:36:52+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondalpress.it\/riconoscimento\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fondalpress.it\/riconoscimento\/#primaryimage","url":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/b3.webp","contentUrl":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/b3.webp","width":850,"height":478},{"@type":"WebSite","@id":"https:\/\/fondalpress.it\/#website","url":"https:\/\/fondalpress.it\/","name":"Fondalpress","description":"High Pressure Die-casting of Aluminium Alloys","publisher":{"@id":"https:\/\/fondalpress.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondalpress.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fondalpress.it\/#organization","name":"Fondalpress","url":"https:\/\/fondalpress.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fondalpress.it\/#\/schema\/logo\/image\/","url":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/logo-dark.png","contentUrl":"https:\/\/fondalpress.it\/wp-content\/uploads\/2023\/12\/logo-dark.png","width":374,"height":41,"caption":"Fondalpress"},"image":{"@id":"https:\/\/fondalpress.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fondalpress.it\/#\/schema\/person\/2803dd62ef580b5b3a488fe8d9ead038","name":"9p8rf","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f05c451de1e00b26ac8f97e593218f403bdeec68c79d0f285b9cd8ca6b14a25f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f05c451de1e00b26ac8f97e593218f403bdeec68c79d0f285b9cd8ca6b14a25f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f05c451de1e00b26ac8f97e593218f403bdeec68c79d0f285b9cd8ca6b14a25f?s=96&d=mm&r=g","caption":"9p8rf"},"sameAs":["https:\/\/fondalpress.it"],"url":"https:\/\/fondalpress.it\/de\/author\/9p8rf\/"}]}},"_links":{"self":[{"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/posts\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":5,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"predecessor-version":[{"id":583,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/posts\/138\/revisions\/583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/media\/1199"}],"wp:attachment":[{"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fondalpress.it\/de\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}